{"id":2838,"date":"2022-12-03T05:53:07","date_gmt":"2022-12-03T05:53:07","guid":{"rendered":"http:\/\/finestwp.com\/vervoer\/?page_id=2838"},"modified":"2026-05-13T15:51:43","modified_gmt":"2026-05-13T07:51:43","slug":"contact","status":"publish","type":"page","link":"http:\/\/www.ftsline.com.cn\/ftscms\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2838\" class=\"elementor elementor-2838\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-396e8d0 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"396e8d0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec34940\" data-id=\"ec34940\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7399ab elementor-widget elementor-widget-google_maps\" data-id=\"e7399ab\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=London%20Eye%2C%20London%2C%20United%20Kingdom&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"London Eye, London, United Kingdom\"\n\t\t\t\t\taria-label=\"London Eye, London, United Kingdom\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bffa0a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bffa0a9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1d399ce\" data-id=\"1d399ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cf3393 elementor-widget elementor-widget-heading\" data-id=\"2cf3393\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Have Questions? <br>Get in touch!<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e3f4c7 contact-page-title elementor-widget elementor-widget-heading\" data-id=\"3e3f4c7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Office Info<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b1227d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b1227d7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8a6d561\" data-id=\"8a6d561\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f627a8 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"7f627a8\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\" flaticon-telephone-1\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-baeab29\" data-id=\"baeab29\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-436b2b0 elementor-widget elementor-widget-text-editor\" data-id=\"436b2b0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>+86 138 2378 0295<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e35349a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e35349a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9d2b46a\" data-id=\"9d2b46a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-442ed27 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"442ed27\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\" flaticon-envelope-1\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a2f7c2f\" data-id=\"a2f7c2f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac9af29 elementor-widget elementor-widget-text-editor\" data-id=\"ac9af29\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>lsc@ftsline.com<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-29efc49 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29efc49\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c77a447\" data-id=\"c77a447\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20bd57e elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"20bd57e\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\" flaticon-pin\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-431c0b0\" data-id=\"431c0b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-952de7e elementor-widget elementor-widget-text-editor\" data-id=\"952de7e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>1105-1106, Huaide International Rental and Sales Center, Bao&#8217;an District, Shenzhen, Shenzhen City, Guangdong Province, China<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4561956\" data-id=\"4561956\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e1e85c elementor-widget elementor-widget-heading\" data-id=\"3e1e85c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Any Query?<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21360bb elementor-widget elementor-widget-shortcode\" data-id=\"21360bb\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2928-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"2928\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ftscms\/wp-json\/wp\/v2\/pages\/2838#wpcf7-f2928-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"2928\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2928-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<section class=\"contact-page\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-xl-12\">\n\t\t\t\t<div class=\"asked-any-query\">\n\t\t\t\t\t<div class=\"contact-form\">\n\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t<div class=\"col-xl-6 col-md-6 col-sm-12\">\n\t\t\t\t\t\t\t\t<div class=\"form-group mb_20\">\n\t\t\t\t\t\t\t\t\t<p><label>Your name:<\/label><i class=\"flaticon-user\"><\/i><span class=\"wpcf7-form-control-wrap\" data-name=\"text-810\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter your name\" value=\"\" type=\"text\" name=\"text-810\" \/><\/span>\n\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-xl-6 col-md-6 col-sm-12\">\n\t\t\t\t\t\t\t\t<div class=\"form-group mb_20\">\n\t\t\t\t\t\t\t\t\t<p><label>Your Mobile:<\/label><i class=\"flaticon-telephone-2\"><\/i><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-498\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" placeholder=\"Enter your mobile\" value=\"\" type=\"tel\" name=\"tel-498\" \/><\/span>\n\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-xl-6 col-md-6 col-sm-12\">\n\t\t\t\t\t\t\t\t<div class=\"form-group mb_20\">\n\t\t\t\t\t\t\t\t\t<p><label>Email Address :<\/label><i class=\"flaticon-envelope\"><\/i><span class=\"wpcf7-form-control-wrap\" data-name=\"email-896\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email Address\" value=\"\" type=\"email\" name=\"email-896\" \/><\/span>\n\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-xl-6 col-md-6 col-sm-12\">\n\t\t\t\t\t\t\t\t<div class=\"form-group mb_20\">\n\t\t\t\t\t\t\t\t\t<p><label>Subject :<\/label><i class=\"flaticon-prescription\"><\/i><span class=\"wpcf7-form-control-wrap\" data-name=\"text-810\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Subject\" value=\"\" type=\"text\" name=\"text-810\" \/><\/span>\n\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-xl-12 col-md-12 col-sm-12\">\n\t\t\t\t\t\t\t\t<div class=\"form-group message-box mb_20\">\n\t\t\t\t\t\t\t\t\t<p><label>Subject :<\/label><i class=\"flaticon-telegram\"><\/i><span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-532\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Message\" name=\"textarea-532\"><\/textarea><\/span>\n\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p><button class=\"button-style-three mb_20\"><i class=\"flaticon-document\"><\/i>Contact Us<\/button>\n\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Have Questions? Get in touch! Office Info +86 138 2378  [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"tpl-default-elementor.php","meta":{"footnotes":""},"class_list":["post-2838","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.ftsline.com.cn\/ftscms\/wp-json\/wp\/v2\/pages\/2838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.ftsline.com.cn\/ftscms\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.ftsline.com.cn\/ftscms\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.ftsline.com.cn\/ftscms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.ftsline.com.cn\/ftscms\/wp-json\/wp\/v2\/comments?post=2838"}],"version-history":[{"count":6,"href":"http:\/\/www.ftsline.com.cn\/ftscms\/wp-json\/wp\/v2\/pages\/2838\/revisions"}],"predecessor-version":[{"id":5424,"href":"http:\/\/www.ftsline.com.cn\/ftscms\/wp-json\/wp\/v2\/pages\/2838\/revisions\/5424"}],"wp:attachment":[{"href":"http:\/\/www.ftsline.com.cn\/ftscms\/wp-json\/wp\/v2\/media?parent=2838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}